{"id":65,"date":"2023-06-07T11:29:22","date_gmt":"2023-06-07T10:29:22","guid":{"rendered":"https:\/\/anogov.com\/home\/?page_id=65"},"modified":"2026-08-14T14:10:50","modified_gmt":"2026-08-14T14:10:50","slug":"faqs","status":"publish","type":"page","link":"https:\/\/anogov.com\/home\/faqs\/","title":{"rendered":"FAQS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"65\" class=\"elementor elementor-65\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b3c2cff elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7b3c2cff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e55f0d7\" data-id=\"3e55f0d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2035a14 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2035a14\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 08-12-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Perguntas Frequentes<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ad37df elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"3ad37df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df2f5e9\" data-id=\"df2f5e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa1fb4a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"aa1fb4a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">1. Enquadramento<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df9ae1 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2df9ae1\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d1f7b0\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2df9ae1\">\n                        <a href=\"#collapse-56b6b456a98754d1f7b0\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d1f7b0\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d1f7b0\">\n                            \n                            <span class=\"ekit-accordion-title\">1.1 Enquadramento legal<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d1f7b0\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-2df9ae1\" data-parent=\"#accordion-6a98754d1f7b0\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"ufaq-faq-body ufaq-body-1264\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\">A plataforma anoGov cumpre todos os requisitos legais estabelecidos pelo Decreto-Lei n\u00ba18\/2008, de 29 de janeiro de 2008, que aprova o C\u00f3digo de Contratos P\u00fablicos (CCP), e pelas respetivas emendas e republica\u00e7\u00f5es. Esta legisla\u00e7\u00e3o \u00e9 aplic\u00e1vel a qualquer contrato que, independentemente da designa\u00e7\u00e3o e natureza, seja celebrado por uma das Entidades Adjudicantes referidas no art.\u00ba 2 do CCP.<\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f48c79b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"f48c79b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fa97cc\" data-id=\"3fa97cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-976aa1a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"976aa1a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">2. Registo<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aac3d06 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"aac3d06\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d1ffee\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-aac3d06\">\n                        <a href=\"#collapse-47edda26a98754d1ffee\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-47edda26a98754d1ffee\" aria-expanded=\"false\" aria-controls=\"Collapse-47edda26a98754d1ffee\">\n                            \n                            <span class=\"ekit-accordion-title\">2.1 Como fazer o meu registo de Fornecedor?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-47edda26a98754d1ffee\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-aac3d06\" data-parent=\"#accordion-6a98754d1ffee\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Clique\u00a0<a href=\"https:\/\/anogov.com\/home\/novo-registo\/\">aqui<\/a>\u00a0e siga as instru\u00e7\u00f5es.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-aac3d06\">\n                        <a href=\"#collapse-706c5b66a98754d1ffee\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-706c5b66a98754d1ffee\" aria-expanded=\"false\" aria-controls=\"Collapse-706c5b66a98754d1ffee\">\n                            \n                            <span class=\"ekit-accordion-title\">2.2 Conclu\u00ed o meu registo, mas ainda n\u00e3o tenho o acesso ativo<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-706c5b66a98754d1ffee\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-aac3d06\" data-parent=\"#accordion-6a98754d1ffee\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>De forma a garantir o cumprimento de todas as regras de seguran\u00e7a decorrentes da Certifica\u00e7\u00e3o ISO 27001, o processo de registo ficar\u00e1 conclu\u00eddo at\u00e9 <strong>3 dias \u00fateis<\/strong>, respeitando os princ\u00edpios de disponibiliza\u00e7\u00e3o e livre acesso do artigo 28.\u00ba da Lei 96\/2015.<\/p><p>A partir desse momento, poder\u00e1 utilizar a plataforma anoGov desta entidade e tirar partido da sua vasta gama de funcionalidades.<\/p><p>NOTA: Se aderiu ao servi\u00e7o \"<strong>Registo \u00danico<\/strong>\" poder\u00e1, ap\u00f3s terminar a inser\u00e7\u00e3o de dados, aceder \u00e0 plataforma de imediato.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-620d360 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"620d360\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-290a1f6\" data-id=\"290a1f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33c0781 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"33c0781\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">3. Recupera\u00e7\u00e3o de acesso\/ Ativa\u00e7\u00e3o de utilizador<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8b460 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"6f8b460\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d207f0\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-6f8b460\">\n                        <a href=\"#collapse-56b6b456a98754d207f0\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d207f0\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d207f0\">\n                            \n                            <span class=\"ekit-accordion-title\">3.1 Recupera\u00e7\u00e3o de palavra-passe<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d207f0\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-6f8b460\" data-parent=\"#accordion-6a98754d207f0\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"ufaq-faq-body ufaq-body-1264\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\"><div class=\"ufaq-faq-body ufaq-body-26830\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\"><p>Caso tenha perdido o acesso \u00e0 plataforma eletr\u00f3nica de contrata\u00e7\u00e3o p\u00fablica anoGov, pelo facto de n\u00e3o se recordar da palavra-passe, ser\u00e1 necess\u00e1rio recuperar o acesso (ou seja, definir as credenciais para aceder \u00e0 plataforma). Para isso, deve efetuar os seguintes passos:<\/p><p><strong>Passo 1<\/strong> - Aceda \u00e0 p\u00e1gina de anoGov de uma entidade adjudicante \u00e0 sua escolha e selecione a op\u00e7\u00e3o <strong>\u201c<span style=\"text-decoration: underline\">Definir\/Recuperar palavra-passe<\/span>\u201d<\/strong><\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9365\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/001.png\" alt=\"\" width=\"482\" height=\"217\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/001.png 482w, https:\/\/anogov.com\/home\/wp-content\/uploads\/001-300x135.png 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/p><p>\u00a0<\/p><p>\u00a0<\/p><p><strong>Passo 2<\/strong> \u2013 Identifique o e-mail do utilizador para o qual \u00e9 necess\u00e1rio efetuar a recupera\u00e7\u00e3o de acesso \u00e0 plataforma<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><p><img decoding=\"async\" class=\"size-full wp-image-9086\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador-a-recuperar.png\" alt=\"dados do utilizador a recuperar\" width=\"522\" height=\"362\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador-a-recuperar.png 522w, https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador-a-recuperar-300x208.png 300w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><\/p><\/figure><\/div><p><strong>Passo 3<\/strong> - Ap\u00f3s efetuar o passo 2, o utilizador em quest\u00e3o receber\u00e1 um e-mail com um c\u00f3digo de valida\u00e7\u00e3o (poder\u00e1 demorar at\u00e9 10 minutos). Esta informa\u00e7\u00e3o \u00e9 apresentada na p\u00e1gina da plataforma<\/p><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><p><img decoding=\"async\" class=\"size-medium wp-image-9087\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/email-enviado-com-sucesso-300x96.png\" alt=\"email enviado com sucesso\" width=\"300\" height=\"96\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/email-enviado-com-sucesso-300x96.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/email-enviado-com-sucesso.png 333w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/figure><p><strong>Passo 4<\/strong> - Ap\u00f3s a rece\u00e7\u00e3o do e-mail com o c\u00f3digo de ativa\u00e7\u00e3o deve efetuar a defini\u00e7\u00e3o da palavra-passe premindo o bot\u00e3o \u201caqui\u201d<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9324\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/aqui.png\" alt=\"\" width=\"698\" height=\"196\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/aqui.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/aqui-300x84.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/aqui-600x168.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><\/div><\/div><\/div><\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-6f8b460\">\n                        <a href=\"#collapse-5d04f966a98754d207f0\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5d04f966a98754d207f0\" aria-expanded=\"false\" aria-controls=\"Collapse-5d04f966a98754d207f0\">\n                            \n                            <span class=\"ekit-accordion-title\">3.2 Tem um novo certificado?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5d04f966a98754d207f0\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-6f8b460\" data-parent=\"#accordion-6a98754d207f0\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"ufaq-faq-body ufaq-body-1264\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\"><div class=\"ufaq-faq-body ufaq-body-26830\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\"><p>Caso tenha perdido o acesso \u00e0 plataforma eletr\u00f3nica de contrata\u00e7\u00e3o p\u00fablica anoGov, pelo facto de estar a utilizar um novo certificado digital qualificado e necessita de associar o mesmo ao seu registo, deve efetuar os seguintes passos.<\/p><p><strong>Passo 1<\/strong> - Aceda \u00e0 p\u00e1gina de anoGov de uma entidade adjudicante \u00e0 sua escolha e selecione a op\u00e7\u00e3o \u201c<strong><span style=\"text-decoration: underline\">Tem um novo certificado?<\/span><\/strong>\u201d<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9364\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/002.png\" alt=\"\" width=\"482\" height=\"217\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/002.png 482w, https:\/\/anogov.com\/home\/wp-content\/uploads\/002-300x135.png 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/p><p>\u00a0<\/p><p><strong>Passo 2<\/strong> \u2013 Este processo consiste em identificar a empresa e o utilizador para o qual \u00e9 necess\u00e1rio efetuar a recupera\u00e7\u00e3o de acesso \u00e0 plataforma<\/p><div class=\"wp-block-image\"><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9105\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/utilizador-tem-um-novo-certificado.png\" alt=\"utilizador tem um novo certificado\" width=\"522\" height=\"374\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/utilizador-tem-um-novo-certificado.png 522w, https:\/\/anogov.com\/home\/wp-content\/uploads\/utilizador-tem-um-novo-certificado-300x215.png 300w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><\/p><figure class=\"aligncenter size-large\"><\/figure><\/div><p><strong>Passo 3<\/strong> - Ap\u00f3s efetuar este procedimento, \u00e9 enviado um email para o endere\u00e7o indicado\/registado (poder\u00e1 demorar at\u00e9 10 minutos. Esta informa\u00e7\u00e3o \u00e9 apresentada na p\u00e1gina da plataforma<\/p><div class=\"wp-block-image\"><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9098\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/email-enviado-com-sucesso-10min.png\" alt=\"email enviado com sucesso 10min\" width=\"300\" height=\"152\" \/><\/p><figure class=\"aligncenter size-large\"><\/figure><\/div><\/div><\/div><\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-6f8b460\">\n                        <a href=\"#collapse-47edda26a98754d207f0\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-47edda26a98754d207f0\" aria-expanded=\"false\" aria-controls=\"Collapse-47edda26a98754d207f0\">\n                            \n                            <span class=\"ekit-accordion-title\">3.3 Associa\u00e7\u00e3o de certificado<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-47edda26a98754d207f0\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-6f8b460\" data-parent=\"#accordion-6a98754d207f0\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><strong>Associa\u00e7\u00e3o de certificado v\u00eddeo:<\/strong><\/p><p><div style=\"width: 800px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-65-1\" width=\"800\" height=\"469\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/Associacao-Certificado-Anogov-1.m4v?_=1\" \/><a href=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/Associacao-Certificado-Anogov-1.m4v\">https:\/\/anogov.com\/home\/wp-content\/uploads\/Associacao-Certificado-Anogov-1.m4v<\/a><\/video><\/div><\/p><p><strong>Associa\u00e7\u00e3o de certificado passo a passo:<\/strong><\/p><p><strong>Passo 1<\/strong> \u2013 Ap\u00f3s a rece\u00e7\u00e3o do email \u201cSenha de ativa\u00e7\u00e3o\u201d, dever\u00e1 efetuar a ativa\u00e7\u00e3o do utilizador selecionando a op\u00e7\u00e3o \u201cclique aqui\u201d no email<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9095\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/email-associar-certificado.png\" alt=\"email associar certificado\" width=\"626\" height=\"433\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/email-associar-certificado.png 626w, https:\/\/anogov.com\/home\/wp-content\/uploads\/email-associar-certificado-300x208.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/email-associar-certificado-600x415.png 600w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/p><p>Ser\u00e1 apresentada a seguinte janela<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9096\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/ecra-associacao-de-certificado.png\" alt=\"ecr\u00e3 associa\u00e7\u00e3o de certificado\" width=\"698\" height=\"333\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/ecra-associacao-de-certificado.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/ecra-associacao-de-certificado-300x143.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/ecra-associacao-de-certificado-600x286.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><div class=\"wp-block-image\">\u00a0<\/div><p><strong>Passo 2<\/strong> \u2013 Carregue na op\u00e7\u00e3o \u201cCarregar certificados\u201d e ser\u00e1 descarregado um ficheiro em JNLP que dever\u00e1 abrir com a aplica\u00e7\u00e3o Java<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9111\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/ficheiro-JNLP.png\" alt=\"ficheiro JNLP\" width=\"312\" height=\"106\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/ficheiro-JNLP.png 312w, https:\/\/anogov.com\/home\/wp-content\/uploads\/ficheiro-JNLP-300x102.png 300w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/><\/p><p><strong>Passo 3<\/strong> \u2013 De seguida aceda \u00e0 op\u00e7\u00e3o \u201cListar \/ atualizar certificados\u201d e adicione o novo Certificado Digital Qualificado que est\u00e1 inserido na sua m\u00e1quina clicando em \u201cAdicionar\u201d, na listagem de certificados<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9229\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/adicionar-certificados.png\" alt=\"adicionar certificados\" width=\"698\" height=\"279\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/adicionar-certificados.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/adicionar-certificados-300x120.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/adicionar-certificados-600x240.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><p><strong>Passo 4<\/strong> \u2013 Por fim, selecione o bot\u00e3o \u201cEnviar\u201d para concluir o processo de ativa\u00e7\u00e3o de utilizador<\/p><p><strong>NOTAS:<\/strong><\/p><ol><li class=\"ewd-ufaq-post-margin ufaq-faq-post\">Dever\u00e1 selecionar a op\u00e7\u00e3o de autentica\u00e7\u00e3o para conseguir efetuar a autentica\u00e7\u00e3o na plataforma e a op\u00e7\u00e3o de assinatura caso o certificado seja utilizado para a assinatura de documentos.<\/li><li class=\"ewd-ufaq-post-margin ufaq-faq-post\">Se estiver a utilizar os certificados da Multicert ou cart\u00e3o do cidad\u00e3o deve adicionar os dois certificados o de autentica\u00e7\u00e3o e de assinatura. Se utilizar o certificado da DigitalSign apenas ter\u00e1 um certificado para adicionar.<\/li><li>Caso pretenda utilizar a componente de assinatura e a mesma n\u00e3o esteja ativa, dever\u00e1 entrar em contacto com a entidade certificadora do seu certificado.<\/li><\/ol><p>.......................................................<\/p><p>Aproveitamos esta oportunidade para informar que um CDQ \u2013 Certificado Digital Qualificado cont\u00e9m informa\u00e7\u00e3o sens\u00edvel relativa \u00e0 pessoa e\/ou organiza\u00e7\u00e3o a que pertence, ainda que esteja fora do prazo de validade, ou seja, j\u00e1 tenha expirado. Para evitar preju\u00edzos resultantes do uso indevido ou do acesso n\u00e3o autorizado por parte de terceiros, aconselhamos a destrui\u00e7\u00e3o do dispositivo de forma a invalid\u00e1-lo definitivamente.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90094d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"90094d9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d155bd\" data-id=\"0d155bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ba5c48 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8ba5c48\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">4. Certificados Digitais Qualificados<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac95561 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"ac95561\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d212af\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-ac95561\">\n                        <a href=\"#collapse-56b6b456a98754d212af\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d212af\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d212af\">\n                            \n                            <span class=\"ekit-accordion-title\">4.1 Como obter um certificado Digital Qualificado?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d212af\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-ac95561\" data-parent=\"#accordion-6a98754d212af\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Clique\u00a0<a href=\"https:\/\/anogov.com\/home\/certificados-digitais-qualificados\/\">aqui<\/a>\u00a0e siga as instru\u00e7\u00f5es.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-ac95561\">\n                        <a href=\"#collapse-3c129316a98754d212af\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-3c129316a98754d212af\" aria-expanded=\"false\" aria-controls=\"Collapse-3c129316a98754d212af\">\n                            \n                            <span class=\"ekit-accordion-title\">4.2 Quanto tempo demora a obter o certificado?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-3c129316a98754d212af\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-ac95561\" data-parent=\"#accordion-6a98754d212af\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Em m\u00e9dia, um Certificado Digital Qualificado demora\u00a0<strong>5 dias \u00fateis<\/strong>\u00a0a ser emitido. Os pedidos urgentes s\u00e3o emitidos em 24 horas, mas t\u00eam de ser levantados pelo titular nas instala\u00e7\u00f5es da Entidade Emissora.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-ac95561\">\n                        <a href=\"#collapse-828de7f6a98754d212af\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-828de7f6a98754d212af\" aria-expanded=\"false\" aria-controls=\"Collapse-828de7f6a98754d212af\">\n                            \n                            <span class=\"ekit-accordion-title\">4.3 Posso usar o meu Cart\u00e3o de Cidad\u00e3o para me registar?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-828de7f6a98754d212af\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-ac95561\" data-parent=\"#accordion-6a98754d212af\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Sim, o Cart\u00e3o de Cidad\u00e3o \u00e9 um Certificado Digital Qualificado e, como tal, pode ser utilizado na plataforma.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-ac95561\">\n                        <a href=\"#collapse-b83a55e6a98754d212af\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-b83a55e6a98754d212af\" aria-expanded=\"false\" aria-controls=\"Collapse-b83a55e6a98754d212af\">\n                            \n                            <span class=\"ekit-accordion-title\">4.4 N\u00e3o estou a conseguir usar o meu CDQ. O que posso fazer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-b83a55e6a98754d212af\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-ac95561\" data-parent=\"#accordion-6a98754d212af\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Clique nos links abaixo para confirmar que consegue aceder \u00e0 lista de certificados Revogados (CRL) de cada Entidade Emissora. S\u00f3 precisa de confirmar o acesso aos links, n\u00e3o \u00e9 necess\u00e1rio descarregar os ficheiros:<\/p><ul><li><a href=\"http:\/\/pki.multicert.com\/cert\/MULTICERT_CA\/mca_001.cer\" target=\"_blank\" rel=\"noopener\">Multicert<\/a><\/li><li><a href=\"http:\/\/onsitecrl.trustwise.com\/BritishTelecommunicationsplcBTDigitalSignQualifiedCA\/LatestCRL.crl\" target=\"_blank\" rel=\"noopener\">Digitalsign<\/a><\/li><li><a href=\"http:\/\/pki.cartaodecidadao.pt\/publico\/lrc\/cc_sub-ec_cidadao_autenticacao_crl0008_delta_p0001.crl\" target=\"_blank\" rel=\"noopener\">Cart\u00e3o de Cidad\u00e3o<\/a><\/li><\/ul>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-ac95561\">\n                        <a href=\"#collapse-1c804296a98754d212af\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1c804296a98754d212af\" aria-expanded=\"false\" aria-controls=\"Collapse-1c804296a98754d212af\">\n                            \n                            <span class=\"ekit-accordion-title\">4.5 Posso usar chave m\u00f3vel digital para submeter minha proposta?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1c804296a98754d212af\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-ac95561\" data-parent=\"#accordion-6a98754d212af\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Sim, j\u00e1 \u00e9 poss\u00edvel utilizar a <strong>Chave M\u00f3vel Digital (CMD)<\/strong> para assinar submiss\u00f5es na plataforma.<\/p><p>Para ativar esta funcionalidade, dever\u00e1 primeiro efetuar o registo na aplica\u00e7\u00e3o Autentica\u00e7\u00e3o.gov, seguindo os passos abaixo:<\/p><p><strong>Passo 1<\/strong> - Abra a aplica\u00e7\u00e3o autentica\u00e7\u00e3o.gov<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-9132\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/autenticacao.gov_.png\" alt=\"autentica\u00e7\u00e3o.gov\" width=\"372\" height=\"420\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/autenticacao.gov_.png 504w, https:\/\/anogov.com\/home\/wp-content\/uploads\/autenticacao.gov_-265x300.png 265w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/><\/p><p><strong>Passo 2<\/strong> - Selecione o \u00edcone de sino dispon\u00edvel na parte inferior da aplica\u00e7\u00e3o<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9133\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/notificacoes-autenticacao.gov_.png\" alt=\"notifica\u00e7\u00f5es autentica\u00e7\u00e3o.gov\" width=\"171\" height=\"95\" \/><\/p><p><strong>Passo 3<\/strong> -\u00a0 Surgir\u00e1 o centro das notifica\u00e7\u00f5es, com a notifica\u00e7\u00e3o a dar a possibilidade de registar a chave m\u00f3vel para assinar em outras aplica\u00e7\u00f5es<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9134\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/registo-chave-movel.png\" alt=\"registo chave m\u00f3vel\" width=\"698\" height=\"477\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/registo-chave-movel.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/registo-chave-movel-300x205.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/registo-chave-movel-600x410.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><p><strong>Passo 4<\/strong> - Ap\u00f3s regist\u00e1-la, inicie novamente o processo de submiss\u00e3o na plataforma a chave m\u00f3vel j\u00e1 lhe aparecer\u00e1 como op\u00e7\u00e3o de certificado<\/p><p>NOTA - O nome do titular do certificado da chave m\u00f3vel fica em letras min\u00fasculas, diferente do certificado do cart\u00e3o de cidad\u00e3o onde o nome do titular aparece todo em letras mai\u00fasculas.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0258ec elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"f0258ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b0418f\" data-id=\"8b0418f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c08a830 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c08a830\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">5. Selos Temporais<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a52d6 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"52a52d6\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d21b89\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-52a52d6\">\n                        <a href=\"#collapse-56b6b456a98754d21b89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d21b89\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d21b89\">\n                            \n                            <span class=\"ekit-accordion-title\">5.1 Para que servem os selos temporais?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d21b89\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-52a52d6\" data-parent=\"#accordion-6a98754d21b89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"ufaq-faq-body ufaq-body-1264\"><div class=\"ewd-ufaq-post-margin ufaq-faq-post\">Os selos temporais atestam a data e hora de cria\u00e7\u00e3o e submiss\u00e3o de um documento.<\/div><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-52a52d6\">\n                        <a href=\"#collapse-eb329ed6a98754d21b89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-eb329ed6a98754d21b89\" aria-expanded=\"false\" aria-controls=\"Collapse-eb329ed6a98754d21b89\">\n                            \n                            <span class=\"ekit-accordion-title\">5.2 Qual \u00e9 o seu enquadramento legal?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-eb329ed6a98754d21b89\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-52a52d6\" data-parent=\"#accordion-6a98754d21b89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Os selos temporais s\u00e3o um requisito legal da contrata\u00e7\u00e3o p\u00fablica eletr\u00f3nica. A plataforma anoGov cumpre o disposto na al\u00ednea a 5 do Despacho n.\u00ba 10583\/2014, de 6 de agosto, publicado no DRE 2\u00aa S\u00e9rie, de 14 de agosto. Aceitamos, desde 27 de setembro de 2014, os certificados de valida\u00e7\u00e3o cronol\u00f3gica emitidos pelas entidades credenciadas para o efeito e constantes na TSL publicada pelo GNS (Gabinete Nacional de Seguran\u00e7a).<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-52a52d6\">\n                        <a href=\"#collapse-31c35ce6a98754d21b89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-31c35ce6a98754d21b89\" aria-expanded=\"false\" aria-controls=\"Collapse-31c35ce6a98754d21b89\">\n                            \n                            <span class=\"ekit-accordion-title\">5.3 Como posso obter selos temporais?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-31c35ce6a98754d21b89\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-52a52d6\" data-parent=\"#accordion-6a98754d21b89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Clique\u00a0<a href=\"https:\/\/anogov.com\/home\/selos-temporais\/\">aqui<\/a>\u00a0e siga as instru\u00e7\u00f5es.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-52a52d6\">\n                        <a href=\"#collapse-c00c2076a98754d21b89\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-c00c2076a98754d21b89\" aria-expanded=\"false\" aria-controls=\"Collapse-c00c2076a98754d21b89\">\n                            \n                            <span class=\"ekit-accordion-title\">5.4 Como posso adicionar os meus selos \u00e0 plataforma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-c00c2076a98754d21b89\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-52a52d6\" data-parent=\"#accordion-6a98754d21b89\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><strong>A parametriza\u00e7\u00e3o dos selos interoper\u00e1veis \u00e9 feita no momento da submiss\u00e3o.<\/strong><\/p><p>Dever\u00e1 clicar na op\u00e7\u00e3o \u201c<strong>Submeter\u201d<\/strong> na \u00e1rea dos documentos e responder as seguintes quest\u00f5es:<\/p><ol><li><strong>Deseja adquirir selos temporais:<\/strong> N\u00e3o<\/li><li><strong>Utilizar selos externos:<\/strong> Sim<\/li><li><strong>Nacionalidade da entidade fornecedora:<\/strong> Portuguesa<\/li><li><strong>Escolher a entidade fornecedora<\/strong>: Multicert\/ DigitalSign\/ GlobalStrust \/Marketware<\/li><li><strong>Introduzir o identificador \u00fanico normalizado<\/strong><\/li><li><strong>Colocar um visto<\/strong> no \u201cLi e aceito\u201d<\/li><li>Clicar em \u201c<strong>Prosseguir<\/strong>\u201d<\/li><\/ol><p>Ap\u00f3s estes passos selecionar o<strong> tipo de documento<\/strong> que pretende submeter e clicar na op\u00e7\u00e3o \u201c<strong>Iniciar Submiss\u00e3o<\/strong>\u201d.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f6c881 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"3f6c881\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0611b5a\" data-id=\"0611b5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-509a36c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"509a36c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">6.  Acesso aos Documentos do Procedimento<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c2ddc elementor-widget elementor-widget-elementskit-accordion\" data-id=\"88c2ddc\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d22458\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-88c2ddc\">\n                        <a href=\"#collapse-56b6b456a98754d22458\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d22458\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d22458\">\n                            \n                            <span class=\"ekit-accordion-title\">6.1 Por que raz\u00e3o s\u00f3 consigo ver o An\u00fancio do Procedimento?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d22458\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-88c2ddc\" data-parent=\"#accordion-6a98754d22458\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div>Se est\u00e1 nos \u201c\u00daltimos An\u00fancios\u201d s\u00f3 conseguir\u00e1 ver os An\u00fancios publicados no Di\u00e1rio da Rep\u00fablica (DR) e no Jornal Oficial da Uni\u00e3o Europeia (JOUE).<br \/>Para aceder \u00e0s pe\u00e7as do procedimento deve ir ao menu \u201cProcedimentos\u201d dentro da Entidade Adjudicante. Para tal, aceda \u00e0 p\u00e1gina de <span style=\"text-decoration: underline\"><a href=\"https:\/\/www.anogov.com\/anoGovCentralOE\/concursos_publicos;jsessionid=843caa8f5d8c6cd7eb67354f13c5?0\" target=\"_blank\" rel=\"noopener\">Concursos P\u00fablicos<\/a><\/span> a decorrer, introduza um crit\u00e9rio de pesquisa, como o nome ou o NIF da entidade, e clique em \u201cProcurar\u201d. Depois de localizar o procedimento que pretende, entre no separador \u201cDocumentos\u201d e conseguir\u00e1 aceder aos restantes documentos.<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-88c2ddc\">\n                        <a href=\"#collapse-34897b56a98754d22458\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-34897b56a98754d22458\" aria-expanded=\"false\" aria-controls=\"Collapse-34897b56a98754d22458\">\n                            \n                            <span class=\"ekit-accordion-title\">6.2 N\u00e3o encontro um procedimento conclu\u00eddo\/extinto <\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-34897b56a98754d22458\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-88c2ddc\" data-parent=\"#accordion-6a98754d22458\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div>Para consultar os procedimentos conclu\u00eddos\/extintos, dever\u00e1 aceder \u00e0 <strong>lista de todos os procedimentos<\/strong> e clicar sobre a op\u00e7\u00e3o abaixo selecionada para \u201c<strong>Visualizar Procedimentos Conclu\u00eddos\/Extintos<\/strong>\u201d.<\/div><div>\u00a0<\/div><div><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9156\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/icone-de-olho.png\" alt=\"\u00edcone de olho\" width=\"602\" height=\"105\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/icone-de-olho.png 602w, https:\/\/anogov.com\/home\/wp-content\/uploads\/icone-de-olho-300x52.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/icone-de-olho-600x105.png 600w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-824dd69 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"824dd69\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fd0431\" data-id=\"4fd0431\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a3ce77 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3a3ce77\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">7.  Descarregar Documentos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6193ed elementor-widget elementor-widget-elementskit-accordion\" data-id=\"c6193ed\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d22ca2\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-c6193ed\">\n                        <a href=\"#collapse-56b6b456a98754d22ca2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d22ca2\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d22ca2\">\n                            \n                            <span class=\"ekit-accordion-title\">7.1 Por que raz\u00e3o n\u00e3o consigo descarregar alguns documentos?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d22ca2\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-c6193ed\" data-parent=\"#accordion-6a98754d22ca2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Se a op\u00e7\u00e3o de pr\u00e9-visualiza\u00e7\u00e3o n\u00e3o se encontra dispon\u00edvel, deve descarregar o documento atrav\u00e9s da ferramenta Java. Para isto, deve efetuar os seguintes passos.<\/p><p><strong>Passo 1<\/strong> -\u00a0 Carregue em cima da designa\u00e7\u00e3o da submiss\u00e3o (designa\u00e7\u00e3o sublinhada)<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9160\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-documentos.png\" alt=\"download de documentos\" width=\"580\" height=\"215\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-documentos.png 580w, https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-documentos-300x111.png 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/p><p>\u00a0<\/p><p><strong>Passo 2<\/strong> - Ser\u00e1 descarregado um ficheiro em JNLP que dever\u00e1 abrir com a aplica\u00e7\u00e3o JAVA\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9161\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-ficheiro-jnlp.png\" alt=\"download de ficheiro jnlp\" width=\"370\" height=\"165\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-ficheiro-jnlp.png 370w, https:\/\/anogov.com\/home\/wp-content\/uploads\/download-de-ficheiro-jnlp-300x134.png 300w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><\/p><p>\u00a0<\/p><p><strong>Passo 3 -<\/strong>\u00a0 Ao abrir o Java ser\u00e1 solicitado que voc\u00ea selecione a pasta de destino para a qual pretende que os documentos fiquem armazenados<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9162\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-pasta-de-destino.png\" alt=\"selecionar pasta de destino\" width=\"585\" height=\"509\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-pasta-de-destino.png 585w, https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-pasta-de-destino-300x261.png 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p><p>\u00a0<\/p><p><strong>Passo 4<\/strong> - Em seguida basta carregar na op\u00e7\u00e3o \"Descarregar\" e o download j\u00e1 estar\u00e1 conclu\u00eddo<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9163\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-o-botao-descarregar.png\" alt=\"selecionar o bot\u00e3o descarregar\" width=\"698\" height=\"600\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-o-botao-descarregar.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-o-botao-descarregar-300x258.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/selecionar-o-botao-descarregar-600x516.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1192ad6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1192ad6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-622f531\" data-id=\"622f531\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77cb227 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"77cb227\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">8. Submeter Documentos e Propostas<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f22f74f elementor-widget elementor-widget-elementskit-accordion\" data-id=\"f22f74f\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d23550\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-f22f74f\">\n                        <a href=\"#collapse-921cc536a98754d23550\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-921cc536a98754d23550\" aria-expanded=\"false\" aria-controls=\"Collapse-921cc536a98754d23550\">\n                            \n                            <span class=\"ekit-accordion-title\">8.1 Boas pr\u00e1ticas<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-921cc536a98754d23550\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-f22f74f\" data-parent=\"#accordion-6a98754d23550\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>O ato de submiss\u00e3o de ficheiros\/documentos na plataforma \u00e9 das tarefas mais cr\u00edticas. Por essa raz\u00e3o, apresentamos, abaixo, algumas recomenda\u00e7\u00f5es para garantir a submiss\u00e3o sem constrangimentos.<\/p><p><strong>1.<\/strong> Verifique se o seu certificado digital qualificado est\u00e1 conectado no posto de trabalho e dentro da validade. Caso esteja a utilizar um certificado remoto\/ cloud, dever\u00e1 garantir as condi\u00e7\u00f5es de leitura do mesmo;<\/p><p><strong>2.<\/strong> Os nomes dos ficheiros\/documentos n\u00e3o devem conter caracteres especiais como _ , &amp; \u00e7 \u2018 ~ ^ \u00b4` (Esta informa\u00e7\u00e3o tamb\u00e9m \u00e9 v\u00e1lida para submiss\u00f5es em pastas zip, ou seja, o nome dos ficheiros\/documentos contidos na pasta zip tamb\u00e9m n\u00e3o devem possuir caracteres especiais);<\/p><p><strong>3.<\/strong> Os ficheiros\/documentos n\u00e3o devem estar localizados em pastas de rede, pens ou discos externos. Aconselhamos que os ficheiros\/documentos estejam localizados no ambiente de trabalho do computador utilizado na submiss\u00e3o;<\/p><p><strong>4.<\/strong> No caso de estar a utilizar selos temporais de um fornecedor externo, verifique se o c\u00f3digo introduzido est\u00e1 correto, v\u00e1lido e sem espa\u00e7os ou com \u201cIUN\u201d no in\u00edcio;<\/p><p><strong>Importante:<\/strong> A plataforma cumpre com toda a legisla\u00e7\u00e3o em vigor que lhe \u00e9 aplic\u00e1vel, nomeadamente, a Lei 96\/2015 de 17 de agosto.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-f22f74f\">\n                        <a href=\"#collapse-acfa9886a98754d23550\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-acfa9886a98754d23550\" aria-expanded=\"false\" aria-controls=\"Collapse-acfa9886a98754d23550\">\n                            \n                            <span class=\"ekit-accordion-title\">8.2 Tamanho m\u00e1ximo permitido por ficheiro<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-acfa9886a98754d23550\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-f22f74f\" data-parent=\"#accordion-6a98754d23550\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>O tamanho m\u00e1ximo permitido por ficheiro \u00e9 de 1.5 GB.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5521\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/Aviso-Faqs-300x103.png\" alt=\"Aviso-Faqs\" width=\"300\" height=\"103\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/Aviso-Faqs-300x103.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/Aviso-Faqs.png 371w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-f22f74f\">\n                        <a href=\"#collapse-56b6b456a98754d23550\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-56b6b456a98754d23550\" aria-expanded=\"false\" aria-controls=\"Collapse-56b6b456a98754d23550\">\n                            \n                            <span class=\"ekit-accordion-title\">8.3 J\u00e1 submeti a proposta. Por que raz\u00e3o n\u00e3o consigo ver os documentos carregados?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-56b6b456a98754d23550\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-f22f74f\" data-parent=\"#accordion-6a98754d23550\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Durante a submiss\u00e3o da proposta, os documentos s\u00e3o encriptados e s\u00f3 ficam novamente dispon\u00edveis depois de serem abertos pela Entidade Adjudicante, altura em que ficam tamb\u00e9m acess\u00edveis a todos os concorrentes.<br \/>Contudo, a lista dos ficheiros submetidos pode ser consultada atrav\u00e9s da notifica\u00e7\u00e3o de comprovativo de carregamento.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-f22f74f\">\n                        <a href=\"#collapse-7f581456a98754d23550\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-7f581456a98754d23550\" aria-expanded=\"false\" aria-controls=\"Collapse-7f581456a98754d23550\">\n                            \n                            <span class=\"ekit-accordion-title\">8.4 Os documentos carregados s\u00e3o assinados?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-7f581456a98754d23550\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-f22f74f\" data-parent=\"#accordion-6a98754d23550\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Durante o processo de submiss\u00e3o, a plataforma <strong>assina a submiss\u00e3o<\/strong> com o certificado do utilizador.<\/p><p><strong>Todos os documentos devem ser assinados, antes de serem submetidos, usando um Certificado Digital Qualificado.<\/strong><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-f22f74f\">\n                        <a href=\"#collapse-535077c6a98754d23550\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-535077c6a98754d23550\" aria-expanded=\"false\" aria-controls=\"Collapse-535077c6a98754d23550\">\n                            \n                            <span class=\"ekit-accordion-title\">8.5 Onde submeto a minha proposta?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-535077c6a98754d23550\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-f22f74f\" data-parent=\"#accordion-6a98754d23550\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Para submeter uma proposta, aceda ao procedimento em que pretende concorrer e no qual j\u00e1 se encontra inscrito. Dentro desse procedimento, no separador dos \u201cDocumentos\u201d selecione a op\u00e7\u00e3o \u201cSubmeter+\u201d<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9179\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/separador-documentos.png\" alt=\"separador documentos\" width=\"698\" height=\"78\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/separador-documentos.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/separador-documentos-300x34.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/separador-documentos-600x67.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2451c3e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"2451c3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a057eb\" data-id=\"0a057eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c9612 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f1c9612\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">9. Gest\u00e3o de utilizadores<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d079bd2 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"d079bd2\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a98754d23e2c\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-d079bd2\">\n                        <a href=\"#collapse-921cc536a98754d23e2c\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-921cc536a98754d23e2c\" aria-expanded=\"false\" aria-controls=\"Collapse-921cc536a98754d23e2c\">\n                            \n                            <span class=\"ekit-accordion-title\">9.1 Como posso adicionar novos utilizadores \u00e0 minha empresa?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-921cc536a98754d23e2c\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-d079bd2\" data-parent=\"#accordion-6a98754d23e2c\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ul><li>Ap\u00f3s iniciar sess\u00e3o na p\u00e1gina de entidade adjudicante, aceda \u00e0 sua \u201cGest\u00e3o de utilizadores\u201d, painel dispon\u00edvel no canto superior direito<\/li><\/ul><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9183\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2.png\" alt=\"gest\u00e3o de utilizadores2\" width=\"366\" height=\"190\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2.png 366w, https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2-300x156.png 300w\" sizes=\"(max-width: 366px) 100vw, 366px\" \/><\/p><ul><li>Dentro da gest\u00e3o de utilizadores clique em \u201cAdicionar Utilizador\u201d<\/li><\/ul><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9185\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/adicionar-utilizador.png\" alt=\"adicionar utilizador\" width=\"168\" height=\"40\" \/><\/p><ul><li>Preencha a informa\u00e7\u00e3o solicitada<\/li><\/ul><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9186\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador.png\" alt=\"dados do utilizador\" width=\"698\" height=\"416\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador-300x179.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/dados-do-utilizador-600x358.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><ul><li>Ap\u00f3s preencher os campos, deve aguardar envio de email com as Formas de acesso \u00e0 plataforma e definir suas formas de acesso (atrav\u00e9s de certificado ou email e palavra-passe).<\/li><\/ul><p>\u00a0<\/p><p>NOTA: O email de utilizador n\u00e3o pode ser igual a algum email j\u00e1 registado.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-d079bd2\">\n                        <a href=\"#collapse-acfa9886a98754d23e2c\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-acfa9886a98754d23e2c\" aria-expanded=\"false\" aria-controls=\"Collapse-acfa9886a98754d23e2c\">\n                            \n                            <span class=\"ekit-accordion-title\">9.2 \u00c9 poss\u00edvel eliminar um utilizador na plataforma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-acfa9886a98754d23e2c\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-d079bd2\" data-parent=\"#accordion-6a98754d23e2c\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Por motivos de seguran\u00e7a e integridade dos dados, n\u00e3o nos \u00e9 poss\u00edvel eliminar os registos, pelo que o processo passa por desativar os utilizadores.<\/p><p>Mais informamos que para proceder \u00e0 desativa\u00e7\u00e3o do utilizador, ap\u00f3s iniciar a sess\u00e3o na p\u00e1gina de uma entidade adjudicante onde tenha acedido previamente, dever\u00e1 efetuar os seguintes passos.<\/p><p><strong>Passo 1<\/strong> - Aceder \u00e0 \u201cGest\u00e3o de utilizadores\u201d (no canto superior direito dentro da p\u00e1gina de uma entidade adjudicante)<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9183\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2.png\" alt=\"gest\u00e3o de utilizadores2\" width=\"366\" height=\"190\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2.png 366w, https:\/\/anogov.com\/home\/wp-content\/uploads\/gestao-de-utilizadores2-300x156.png 300w\" sizes=\"(max-width: 366px) 100vw, 366px\" \/><\/p><p><strong>Passo 2 <\/strong>- Selecionar o utilizador pretendido<\/p><p><strong>Passo 3<\/strong> - Selecionar \u201cDesativar\u201d \/ \u201cAtivar\u201d<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9194\" src=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/desativar-utilizador.png\" alt=\"desativar utilizador\" width=\"698\" height=\"259\" srcset=\"https:\/\/anogov.com\/home\/wp-content\/uploads\/desativar-utilizador.png 698w, https:\/\/anogov.com\/home\/wp-content\/uploads\/desativar-utilizador-300x111.png 300w, https:\/\/anogov.com\/home\/wp-content\/uploads\/desativar-utilizador-600x223.png 600w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/p><p>\u00a0<\/p><p>\u00a0<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Perguntas Frequentes 1. Enquadramento 1.1 Enquadramento legal A plataforma anoGov cumpre todos os requisitos legais estabelecidos pelo Decreto-Lei n\u00ba18\/2008, de 29 de janeiro de 2008, que aprova o C\u00f3digo de Contratos P\u00fablicos (CCP), e pelas respetivas emendas e republica\u00e7\u00f5es. Esta legisla\u00e7\u00e3o \u00e9 aplic\u00e1vel a qualquer contrato que, independentemente da designa\u00e7\u00e3o e natureza, seja celebrado por [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-65","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/pages\/65"}],"collection":[{"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":245,"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/pages\/65\/revisions"}],"predecessor-version":[{"id":9368,"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/pages\/65\/revisions\/9368"}],"wp:attachment":[{"href":"https:\/\/anogov.com\/home\/wp-json\/wp\/v2\/media?parent=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}